{"id":2015,"date":"2023-07-24T07:22:41","date_gmt":"2023-07-24T05:22:41","guid":{"rendered":"https:\/\/imaflowtest.fr\/?page_id=689"},"modified":"2023-10-06T11:09:17","modified_gmt":"2023-10-06T09:09:17","slug":"prestation-cytometrie","status":"publish","type":"page","link":"https:\/\/imaflow.com\/index.php\/prestation-cytometrie\/","title":{"rendered":"Prestation Cytom\u00e9trie"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2015\" class=\"elementor elementor-2015\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ab41d8c elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ab41d8c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c131236\" data-id=\"c131236\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad5c9b6 elementor-widget elementor-widget-spacer\" data-id=\"ad5c9b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d468a2 elementor-widget elementor-widget-heading\" data-id=\"7d468a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos prestations en cytom\u00e9trie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-070e7d7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"070e7d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7b5ed87 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7b5ed87\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0ef2e7d\" data-id=\"0ef2e7d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64bc91c elementor-widget elementor-widget-text-editor\" data-id=\"64bc91c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous vous proposons un ensemble de prestations en cytom\u00e9trie en flux multi-param\u00e9trique, en tri cellulaire, et en analyse quantitative de prot\u00e9ines solubles par multiplexage. Gr\u00e2ce \u00e0 nos \u00e9quipements et \u00e0 notre expertise, vous parviendrez \u00e0 caract\u00e9riser et\u00a0 purifier des populations cellulaires pour la recherche fondamentale et\/ou clinique. Les applications cibl\u00e9es sont vari\u00e9es : ph\u00e9notypage des cellules, analyse du cycle cellulaire, apoptose, respiration mitochondriale, etc\u2026<\/p><p>Le personnel d\u00e9di\u00e9 poss\u00e8de une large expertise technologique et scientifique pour la mise en \u0153uvre de projets depuis leur conception, en passant par la pr\u00e9paration des \u00e9chantillons jusqu&rsquo;\u00e0 l&rsquo;analyse des donn\u00e9es et assure les prestations et les formations n\u00e9cessaires.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59ab6f1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"59ab6f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7de06d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7de06d0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7a95a9d\" data-id=\"7a95a9d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ddf93c3 elementor-widget elementor-widget-heading\" data-id=\"ddf93c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mise \u00e0 disposition d\u2019\u00e9quipements \/ Encadrement et accompagnement \u00e0 l\u2019acquisition de donn\u00e9es<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-91ad843 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"91ad843\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f98dd69\" data-id=\"f98dd69\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b49a48 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"2b49a48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1040\" height=\"780\" src=\"https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/IMG_20190605_122325.jpg\" class=\"attachment-full size-full wp-image-2937\" alt=\"\" srcset=\"https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/IMG_20190605_122325.jpg 1040w, https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/IMG_20190605_122325-300x225.jpg 300w, https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/IMG_20190605_122325-1024x768.jpg 1024w, https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/IMG_20190605_122325-768x576.jpg 768w\" sizes=\"(max-width: 1040px) 100vw, 1040px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a65994e\" data-id=\"a65994e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a2067a5 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a2067a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous mettons \u00e0 disposition diff\u00e9rents \u00e9quipements et assurons l\u2019accompagnement n\u00e9cessaire \u00e0 la pr\u00e9paration (enrichissement d\u2019\u00e9chantillons et isolements de populations d\u2019int\u00e9r\u00eat par trieurs magn\u00e9tiques) et l\u2019acquisition\u00a0 des donn\u00e9es de cytom\u00e9trie (cytom\u00e8tres analyseurs conventionnels et spectraux). L\u2019acc\u00e8s aux \u00e9quipements est totalement libre apr\u00e8s que les utilisateurs aient \u00e9t\u00e9 habilit\u00e9s (formation th\u00e9orique et pratique) \u00e0 l\u2019utilisation en autonomie des instruments.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-c90898c elementor-widget elementor-widget-text-editor\" data-id=\"c90898c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La liste compl\u00e8te des \u00e9quipements disponibles \u00e0 la r\u00e9servation est accessible <a href=\"https:\/\/imaflow.com\/index.php\/equipement-cytometrie\/\">ici<\/a> et les tarifs communiqu\u00e9s sur demande.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e4f7cc elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7e4f7cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d96dbd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d96dbd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a5e8bb6\" data-id=\"a5e8bb6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46094d3 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"46094d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prestation de tri cellulaire<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f16875 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"4f16875\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-47f8965 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47f8965\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-29032c6\" data-id=\"29032c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bdb906e elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"bdb906e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/IMG_8244-scaled.jpg\" class=\"attachment-full size-full wp-image-2863\" alt=\"\" srcset=\"https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/IMG_8244-scaled.jpg 2560w, https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/IMG_8244-300x200.jpg 300w, https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/IMG_8244-1024x683.jpg 1024w, https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/IMG_8244-768x512.jpg 768w, https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/IMG_8244-1536x1024.jpg 1536w, https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/IMG_8244-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b6e15af\" data-id=\"b6e15af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c68b5b elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"0c68b5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous r\u00e9alisons des prestations de tri cellulaire \u00e0 partir de diff\u00e9rents \u00e9chantillons biologiques (niveau I et II). Toute prestation doit faire l\u2019objet d\u2019une demande pr\u00e9alable nous permettant de discuter du projet de recherche et d\u2019\u00e9valuer sa faisabilit\u00e9 et\/ou d\u2019adopter la meilleure strat\u00e9gie de tri en fonction du type cellulaire et de l\u2019application cibl\u00e9e.<\/p><p>Note : Les immunomarquages pour le tri cellulaire doivent \u00eatre pris en charge par le demandeur de la prestation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2298d2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f2298d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-897c55f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"897c55f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cb2125a\" data-id=\"cb2125a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-592fea3 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"592fea3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Aide au panel design<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0088f12 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"0088f12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c9bb952 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c9bb952\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b3444cf\" data-id=\"b3444cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55f4a25 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"55f4a25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"703\" height=\"559\" src=\"https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/panel-design.png\" class=\"attachment-full size-full wp-image-2611\" alt=\"\" srcset=\"https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/panel-design.png 703w, https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/panel-design-300x239.png 300w\" sizes=\"(max-width: 703px) 100vw, 703px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-88263ad\" data-id=\"88263ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac8bc2e elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"ac8bc2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p>Gr\u00e2ce \u00e0 diff\u00e9rents outils, nous vous aidons \u00e0 mettre au point vos panels multi-couleurs dans le cadre de l\u2019analyse ph\u00e9notypiques de divers types cellulaires. N\u2019h\u00e9sitez pas \u00e0 nous contacter pour \u00eatre accompagn\u00e9s dans cette \u00e9tape indispensable \u00e0 toute analyse de cytom\u00e9trie en flux.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-aab2911 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"aab2911\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a09b2d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a09b2d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5e206c2\" data-id=\"5e206c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2e1516 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"d2e1516\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Traitement de donn\u00e9es<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee16dcc elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"ee16dcc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2be1282 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2be1282\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1504a9a\" data-id=\"1504a9a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eef6b1a elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"eef6b1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"798\" height=\"440\" src=\"https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/tsne-1.png\" class=\"attachment-full size-full wp-image-2889\" alt=\"\" srcset=\"https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/tsne-1.png 798w, https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/tsne-1-300x165.png 300w, https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/tsne-1-768x423.png 768w\" sizes=\"(max-width: 798px) 100vw, 798px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-182013c\" data-id=\"182013c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd5d809 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"bd5d809\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Diff\u00e9rents logiciels de traitements de donn\u00e9es (FlowJo, SpectroFlo, ModFit LT, etc) sont mis \u00e0 disposition au sein de la plateforme. Nous vous accompagnons, selon les r\u00e8gles de l\u2019art, dans leur prise en main ainsi que dans le traitement (supervis\u00e9 et non supervis\u00e9) de vos donn\u00e9es de cytom\u00e9trie.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-a12a89e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a12a89e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0680c79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0680c79\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d7dae18\" data-id=\"d7dae18\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0aa062 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"c0aa062\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Formation de Cytom\u00e9trie en flux<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6464c6e elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"6464c6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d14186e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d14186e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bf34be1\" data-id=\"bf34be1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-435cd25 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"435cd25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"601\" height=\"399\" src=\"https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/formation.png\" class=\"attachment-full size-full wp-image-2943\" alt=\"\" srcset=\"https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/formation.png 601w, https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/formation-300x199.png 300w\" sizes=\"(max-width: 601px) 100vw, 601px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3eb22b8\" data-id=\"3eb22b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ca4afc elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"9ca4afc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p>Nous proposons aussi bien tout le long de l\u2019ann\u00e9e que sur demande sp\u00e9cifique, des formations \u00e0 la cytom\u00e9trie en flux, adaptables \u00e0 vos th\u00e9matiques et probl\u00e9matiques de recherche. Veuillez nous contacter pour de plus amples informations.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nos prestations en cytom\u00e9trie Nous vous proposons un ensemble de prestations en cytom\u00e9trie en flux multi-param\u00e9trique, en tri cellulaire, et en analyse quantitative de prot\u00e9ines solubles par multiplexage. Gr\u00e2ce \u00e0 nos \u00e9quipements et \u00e0 notre expertise, vous parviendrez \u00e0 caract\u00e9riser et\u00a0 purifier des populations cellulaires pour la recherche fondamentale et\/ou clinique. Les applications cibl\u00e9es sont [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-2015","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prestation Cytom\u00e9trie - Imaflow<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/imaflow.com\/index.php\/prestation-cytometrie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prestation Cytom\u00e9trie - Imaflow\" \/>\n<meta property=\"og:description\" content=\"Nos prestations en cytom\u00e9trie Nous vous proposons un ensemble de prestations en cytom\u00e9trie en flux multi-param\u00e9trique, en tri cellulaire, et en analyse quantitative de prot\u00e9ines solubles par multiplexage. Gr\u00e2ce \u00e0 nos \u00e9quipements et \u00e0 notre expertise, vous parviendrez \u00e0 caract\u00e9riser et\u00a0 purifier des populations cellulaires pour la recherche fondamentale et\/ou clinique. Les applications cibl\u00e9es sont [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/imaflow.com\/index.php\/prestation-cytometrie\/\" \/>\n<meta property=\"og:site_name\" content=\"Imaflow\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-06T09:09:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/IMG_20190605_122325.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/imaflow.com\\\/index.php\\\/prestation-cytometrie\\\/\",\"url\":\"https:\\\/\\\/imaflow.com\\\/index.php\\\/prestation-cytometrie\\\/\",\"name\":\"Prestation Cytom\u00e9trie - Imaflow\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/imaflow.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/imaflow.com\\\/index.php\\\/prestation-cytometrie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/imaflow.com\\\/index.php\\\/prestation-cytometrie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/imaflow.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_20190605_122325.jpg\",\"datePublished\":\"2023-07-24T05:22:41+00:00\",\"dateModified\":\"2023-10-06T09:09:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/imaflow.com\\\/index.php\\\/prestation-cytometrie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/imaflow.com\\\/index.php\\\/prestation-cytometrie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/imaflow.com\\\/index.php\\\/prestation-cytometrie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/imaflow.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_20190605_122325.jpg\",\"contentUrl\":\"https:\\\/\\\/imaflow.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_20190605_122325.jpg\",\"width\":1040,\"height\":780,\"caption\":\"bty\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/imaflow.com\\\/index.php\\\/prestation-cytometrie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/imaflow.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prestation Cytom\u00e9trie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/imaflow.com\\\/#website\",\"url\":\"https:\\\/\\\/imaflow.com\\\/\",\"name\":\"Imaflow\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/imaflow.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/imaflow.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/imaflow.com\\\/#organization\",\"name\":\"Imaflow\",\"url\":\"https:\\\/\\\/imaflow.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/imaflow.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/imaflow.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo-imaflow-quadri-rogne-1-300x133-1.png\",\"contentUrl\":\"https:\\\/\\\/imaflow.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo-imaflow-quadri-rogne-1-300x133-1.png\",\"width\":300,\"height\":133,\"caption\":\"Imaflow\"},\"image\":{\"@id\":\"https:\\\/\\\/imaflow.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/fr.linkedin.com\\\/company\\\/imaflow\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prestation Cytom\u00e9trie - Imaflow","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/imaflow.com\/index.php\/prestation-cytometrie\/","og_locale":"fr_FR","og_type":"article","og_title":"Prestation Cytom\u00e9trie - Imaflow","og_description":"Nos prestations en cytom\u00e9trie Nous vous proposons un ensemble de prestations en cytom\u00e9trie en flux multi-param\u00e9trique, en tri cellulaire, et en analyse quantitative de prot\u00e9ines solubles par multiplexage. Gr\u00e2ce \u00e0 nos \u00e9quipements et \u00e0 notre expertise, vous parviendrez \u00e0 caract\u00e9riser et\u00a0 purifier des populations cellulaires pour la recherche fondamentale et\/ou clinique. Les applications cibl\u00e9es sont [&hellip;]","og_url":"https:\/\/imaflow.com\/index.php\/prestation-cytometrie\/","og_site_name":"Imaflow","article_modified_time":"2023-10-06T09:09:17+00:00","og_image":[{"url":"https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/IMG_20190605_122325.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/imaflow.com\/index.php\/prestation-cytometrie\/","url":"https:\/\/imaflow.com\/index.php\/prestation-cytometrie\/","name":"Prestation Cytom\u00e9trie - Imaflow","isPartOf":{"@id":"https:\/\/imaflow.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/imaflow.com\/index.php\/prestation-cytometrie\/#primaryimage"},"image":{"@id":"https:\/\/imaflow.com\/index.php\/prestation-cytometrie\/#primaryimage"},"thumbnailUrl":"https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/IMG_20190605_122325.jpg","datePublished":"2023-07-24T05:22:41+00:00","dateModified":"2023-10-06T09:09:17+00:00","breadcrumb":{"@id":"https:\/\/imaflow.com\/index.php\/prestation-cytometrie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/imaflow.com\/index.php\/prestation-cytometrie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/imaflow.com\/index.php\/prestation-cytometrie\/#primaryimage","url":"https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/IMG_20190605_122325.jpg","contentUrl":"https:\/\/imaflow.com\/wp-content\/uploads\/2023\/09\/IMG_20190605_122325.jpg","width":1040,"height":780,"caption":"bty"},{"@type":"BreadcrumbList","@id":"https:\/\/imaflow.com\/index.php\/prestation-cytometrie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/imaflow.com\/"},{"@type":"ListItem","position":2,"name":"Prestation Cytom\u00e9trie"}]},{"@type":"WebSite","@id":"https:\/\/imaflow.com\/#website","url":"https:\/\/imaflow.com\/","name":"Imaflow","description":"","publisher":{"@id":"https:\/\/imaflow.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/imaflow.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/imaflow.com\/#organization","name":"Imaflow","url":"https:\/\/imaflow.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/imaflow.com\/#\/schema\/logo\/image\/","url":"https:\/\/imaflow.com\/wp-content\/uploads\/2026\/05\/logo-imaflow-quadri-rogne-1-300x133-1.png","contentUrl":"https:\/\/imaflow.com\/wp-content\/uploads\/2026\/05\/logo-imaflow-quadri-rogne-1-300x133-1.png","width":300,"height":133,"caption":"Imaflow"},"image":{"@id":"https:\/\/imaflow.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/fr.linkedin.com\/company\/imaflow"]}]}},"_links":{"self":[{"href":"https:\/\/imaflow.com\/index.php\/wp-json\/wp\/v2\/pages\/2015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imaflow.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/imaflow.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/imaflow.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/imaflow.com\/index.php\/wp-json\/wp\/v2\/comments?post=2015"}],"version-history":[{"count":15,"href":"https:\/\/imaflow.com\/index.php\/wp-json\/wp\/v2\/pages\/2015\/revisions"}],"predecessor-version":[{"id":3649,"href":"https:\/\/imaflow.com\/index.php\/wp-json\/wp\/v2\/pages\/2015\/revisions\/3649"}],"wp:attachment":[{"href":"https:\/\/imaflow.com\/index.php\/wp-json\/wp\/v2\/media?parent=2015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}